{"id":239,"date":"2025-11-25T04:26:40","date_gmt":"2025-11-25T04:26:40","guid":{"rendered":"https:\/\/designawebsite.co.in\/demo\/golevo\/?post_type=project&#038;p=239"},"modified":"2026-04-29T09:51:32","modified_gmt":"2026-04-29T09:51:32","slug":"dr-clarence-g-oliver-jr","status":"publish","type":"project","link":"https:\/\/designawebsite.co.in\/demo\/golevo\/author-webdesign","title":{"rendered":"Dr. Clarence G. Oliver, Jr."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":240,"template":"","type_of_work":[76,25,28,30,48,49,51],"type_of_industry":[52,57,56,65],"service_categories":[71,75],"class_list":["post-239","project","type-project","status-publish","has-post-thumbnail","hentry","type_of_work-b2c-expertise","type_of_work-branding","type_of_work-copywriting","type_of_work-digital-design","type_of_work-strategy-development","type_of_work-user-experience","type_of_work-website","type_of_industry-arts-culture","type_of_industry-education","type_of_industry-entertainment","type_of_industry-publishing","service_categories-branding","service_categories-web-design-and-development","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dr. Clarence G. Oliver Author Website Project Insights<\/title>\n<meta name=\"description\" content=\"Levo designed a custom branding and website for Dr. Clarence G. Oliver Jr., an author, historian, and educator, going beyond standard templates.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/designawebsite.co.in\/demo\/golevo\/author-webdesign\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Clarence G. Oliver Author Website Project Insights\" \/>\n<meta property=\"og:description\" content=\"Levo designed a custom branding and website for Dr. Clarence G. Oliver Jr., an author, historian, and educator, going beyond standard templates.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/designawebsite.co.in\/demo\/golevo\/author-webdesign\/\" \/>\n<meta property=\"og:site_name\" content=\"Levo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/golevo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T09:51:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-content\/uploads\/2025\/11\/clarence-g-oliver-jr-ed-d-new.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@golevo\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/author-webdesign\\\/\",\"url\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/author-webdesign\\\/\",\"name\":\"Dr. Clarence G. Oliver Author Website Project Insights\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/author-webdesign\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/author-webdesign\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/clarence-g-oliver-jr-ed-d-new.jpg\",\"datePublished\":\"2025-11-25T04:26:40+00:00\",\"dateModified\":\"2026-04-29T09:51:32+00:00\",\"description\":\"Levo designed a custom branding and website for Dr. Clarence G. Oliver Jr., an author, historian, and educator, going beyond standard templates.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/author-webdesign\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/author-webdesign\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/author-webdesign\\\/#primaryimage\",\"url\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/clarence-g-oliver-jr-ed-d-new.jpg\",\"contentUrl\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/clarence-g-oliver-jr-ed-d-new.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Dr. Clarence G. Oliver, Jr.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/author-webdesign\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dr. Clarence G. Oliver, Jr.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/#website\",\"url\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/\",\"name\":\"golevo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/#organization\",\"name\":\"golevo\",\"url\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/sitelogo1.png\",\"contentUrl\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/sitelogo1.png\",\"width\":226,\"height\":144,\"caption\":\"golevo\"},\"image\":{\"@id\":\"https:\\\/\\\/designawebsite.co.in\\\/demo\\\/golevo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/golevo\",\"https:\\\/\\\/x.com\\\/golevo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. Clarence G. Oliver Author Website Project Insights","description":"Levo designed a custom branding and website for Dr. Clarence G. Oliver Jr., an author, historian, and educator, going beyond standard templates.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/designawebsite.co.in\/demo\/golevo\/author-webdesign\/","og_locale":"en_US","og_type":"article","og_title":"Dr. Clarence G. Oliver Author Website Project Insights","og_description":"Levo designed a custom branding and website for Dr. Clarence G. Oliver Jr., an author, historian, and educator, going beyond standard templates.","og_url":"https:\/\/designawebsite.co.in\/demo\/golevo\/author-webdesign\/","og_site_name":"Levo","article_publisher":"https:\/\/www.facebook.com\/golevo","article_modified_time":"2026-04-29T09:51:32+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-content\/uploads\/2025\/11\/clarence-g-oliver-jr-ed-d-new.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@golevo","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/designawebsite.co.in\/demo\/golevo\/author-webdesign\/","url":"https:\/\/designawebsite.co.in\/demo\/golevo\/author-webdesign\/","name":"Dr. Clarence G. Oliver Author Website Project Insights","isPartOf":{"@id":"https:\/\/designawebsite.co.in\/demo\/golevo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/designawebsite.co.in\/demo\/golevo\/author-webdesign\/#primaryimage"},"image":{"@id":"https:\/\/designawebsite.co.in\/demo\/golevo\/author-webdesign\/#primaryimage"},"thumbnailUrl":"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-content\/uploads\/2025\/11\/clarence-g-oliver-jr-ed-d-new.jpg","datePublished":"2025-11-25T04:26:40+00:00","dateModified":"2026-04-29T09:51:32+00:00","description":"Levo designed a custom branding and website for Dr. Clarence G. Oliver Jr., an author, historian, and educator, going beyond standard templates.","breadcrumb":{"@id":"https:\/\/designawebsite.co.in\/demo\/golevo\/author-webdesign\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/designawebsite.co.in\/demo\/golevo\/author-webdesign\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/designawebsite.co.in\/demo\/golevo\/author-webdesign\/#primaryimage","url":"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-content\/uploads\/2025\/11\/clarence-g-oliver-jr-ed-d-new.jpg","contentUrl":"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-content\/uploads\/2025\/11\/clarence-g-oliver-jr-ed-d-new.jpg","width":1920,"height":1080,"caption":"Dr. Clarence G. Oliver, Jr."},{"@type":"BreadcrumbList","@id":"https:\/\/designawebsite.co.in\/demo\/golevo\/author-webdesign\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/designawebsite.co.in\/demo\/golevo\/"},{"@type":"ListItem","position":2,"name":"Dr. Clarence G. Oliver, Jr."}]},{"@type":"WebSite","@id":"https:\/\/designawebsite.co.in\/demo\/golevo\/#website","url":"https:\/\/designawebsite.co.in\/demo\/golevo\/","name":"golevo","description":"","publisher":{"@id":"https:\/\/designawebsite.co.in\/demo\/golevo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/designawebsite.co.in\/demo\/golevo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/designawebsite.co.in\/demo\/golevo\/#organization","name":"golevo","url":"https:\/\/designawebsite.co.in\/demo\/golevo\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/designawebsite.co.in\/demo\/golevo\/#\/schema\/logo\/image\/","url":"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-content\/uploads\/2026\/01\/sitelogo1.png","contentUrl":"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-content\/uploads\/2026\/01\/sitelogo1.png","width":226,"height":144,"caption":"golevo"},"image":{"@id":"https:\/\/designawebsite.co.in\/demo\/golevo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/golevo","https:\/\/x.com\/golevo"]}]}},"_links":{"self":[{"href":"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-json\/wp\/v2\/project\/239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-json\/wp\/v2\/media\/240"}],"wp:attachment":[{"href":"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-json\/wp\/v2\/media?parent=239"}],"wp:term":[{"taxonomy":"type_of_work","embeddable":true,"href":"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-json\/wp\/v2\/type_of_work?post=239"},{"taxonomy":"type_of_industry","embeddable":true,"href":"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-json\/wp\/v2\/type_of_industry?post=239"},{"taxonomy":"service_categories","embeddable":true,"href":"https:\/\/designawebsite.co.in\/demo\/golevo\/wp-json\/wp\/v2\/service_categories?post=239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}